{"id":1343,"count":85,"description":"","link":"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/","name":"Ucraina","slug":"ucraina","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ucraina Archives - Secretele lui Lovendal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhive Ucraina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretele lui Lovendal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/tag\\\/ucraina\\\/\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/tag\\\/ucraina\\\/\",\"name\":\"Ucraina Archives - Secretele lui Lovendal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/tag\\\/ucraina\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/tag\\\/ucraina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ucraina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#website\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\",\"name\":\"Secretele lui Lovendal\",\"description\":\"Site de secrete, stiinta si metafizica - din 2008 -\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#organization\",\"name\":\"Secretele lui Lovendal\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-SLL-iun-2024-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-SLL-iun-2024-1.jpg\",\"width\":771,\"height\":240,\"caption\":\"Secretele lui Lovendal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/secreteleluilovendal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ucraina Archives - Secretele lui Lovendal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/","og_locale":"ro_RO","og_type":"article","og_title":"Arhive Ucraina","og_url":"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/","og_site_name":"Secretele lui Lovendal","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/","url":"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/","name":"Ucraina Archives - Secretele lui Lovendal","isPartOf":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#website"},"breadcrumb":{"@id":"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/#breadcrumb"},"inLanguage":"ro-RO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lovendal.ro\/wp52\/tag\/ucraina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lovendal.ro\/wp52\/"},{"@type":"ListItem","position":2,"name":"Ucraina"}]},{"@type":"WebSite","@id":"https:\/\/www.lovendal.ro\/wp52\/#website","url":"https:\/\/www.lovendal.ro\/wp52\/","name":"Secretele lui Lovendal","description":"Site de secrete, stiinta si metafizica - din 2008 -","publisher":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lovendal.ro\/wp52\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/www.lovendal.ro\/wp52\/#organization","name":"Secretele lui Lovendal","url":"https:\/\/www.lovendal.ro\/wp52\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/logo\/image\/","url":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2024\/06\/cropped-SLL-iun-2024-1.jpg","contentUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2024\/06\/cropped-SLL-iun-2024-1.jpg","width":771,"height":240,"caption":"Secretele lui Lovendal"},"image":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/secreteleluilovendal"]}]}},"_links":{"self":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/tags\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/posts?tags=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}