{"id":73533,"date":"2021-02-11T20:30:06","date_gmt":"2021-02-11T18:30:06","guid":{"rendered":"https:\/\/www.lovendal.ro\/wp52\/?p=73533"},"modified":"2021-02-11T20:30:27","modified_gmt":"2021-02-11T18:30:27","slug":"a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor","status":"publish","type":"post","link":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/","title":{"rendered":"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?"},"content":{"rendered":"<figure id=\"attachment_73534\" aria-describedby=\"caption-attachment-73534\" style=\"width: 348px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-73534\" src=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg\" alt=\"\" width=\"358\" height=\"239\" srcset=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg 358w, https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa-300x200.jpg 300w, https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa-356x239.jpg 356w\" sizes=\"auto, (max-width: 358px) 100vw, 358px\" \/><\/a><figcaption id=\"caption-attachment-73534\" class=\"wp-caption-text\"><strong>Imagine:<\/strong> <a href=\"https:\/\/pixabay.com\/ro\/illustrations\/dinozaur-meteor-impactul-apocalipsa-5277285\/\" target=\"_blank\" rel=\"noopener\"><strong>pixabay.com<\/strong><\/a> (Commons Creative &#8211; free)<\/figcaption><\/figure>\n<p>Se \u015ftie c\u0103, potrivit oamenilor de \u015ftiin\u0163\u0103, dinozaurii au disp\u0103rut de pe fa\u0163a p\u0103m\u00e2ntului \u00een urm\u0103 cu 65 de milioane de ani. Ni s-a tot spus c\u0103 de vin\u0103 ar fi un asteroid sau o comet\u0103, care s-a pr\u0103bu\u015fit pe Terra. Acel corp ceresc trebuie s\u0103 fi fost unul extrem de mare, form\u00e2nd un crater imens \u00een locul \u00een care s-a pr\u0103bu\u015fit pe Terra. Imediat, o und\u0103 de \u015foc a zdruncinat planeta noastr\u0103, iar atmosfera a fost acoperit\u0103 cu nori imen\u015fi de praf, care au r\u0103cit dramatic toat\u0103 suprafa\u0163a Terrei.<\/p>\n<p>Dar, despre ce comet\u0103 sau asteroid a fost vorba? Am citit \u00eentr-o lucrare o ipotez\u0103 foarte interesant\u0103: e posibil ca \u00een trecutul extrem de \u00eendep\u0103rtat, Terra s\u0103 fi avut \u00eenc\u0103 un satelit (\u00eenc\u0103 o Lun\u0103), care, apropiindu-se de P\u0103m\u00e2nt mult prea mult dec\u00e2t actuala Lun\u0103, s-a dezagregat \u00een momentul c\u00e2nd a p\u0103truns \u00een atmosfera terestr\u0103, r\u0103m\u0103\u0219i\u021bele ei distrug\u00e2nd \u00eentreaga via\u021b\u0103 din zona \u00een care a c\u0103zut pe P\u0103m\u00e2nt. A\u0219a s-ar explica dispari\u021bia dinozaurilor.<\/p>\n<p>Ipoteza este una extrem de interesant\u0103, iar eu zic c\u0103 ar trebui luat\u0103 \u00een considerare&#8230; Chiar a fost o perioad\u0103 c\u00e2nd pe Terra puteam vedea doi sateli\u0163i naturali?<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se \u015ftie c\u0103, potrivit oamenilor de \u015ftiin\u0163\u0103, dinozaurii au disp\u0103rut de pe fa\u0163a p\u0103m\u00e2ntului \u00een urm\u0103 cu 65 de milioane de ani. Ni s-a tot spus c\u0103 de vin\u0103 ar fi un asteroid sau o comet\u0103, care s-a pr\u0103bu\u015fit pe &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?\" class=\"read-more button\" href=\"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#more-73533\" aria-label=\"Cite\u0219te mai multe despre A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?\">Cititi mai multe<\/a><\/p>\n","protected":false},"author":1,"featured_media":73534,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11039],"tags":[966,102,2502,160,3459,310,149,105,6987,600],"class_list":["post-73533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-astronomie","tag-asteroid","tag-astronomie","tag-atmosfera","tag-cometa","tag-crater","tag-dinozauri","tag-luna","tag-pamant","tag-praf","tag-satelit","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor? - Secretele lui Lovendal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?\" \/>\n<meta property=\"og:description\" content=\"Se \u015ftie c\u0103, potrivit oamenilor de \u015ftiin\u0163\u0103, dinozaurii au disp\u0103rut de pe fa\u0163a p\u0103m\u00e2ntului \u00een urm\u0103 cu 65 de milioane de ani. Ni s-a tot spus c\u0103 de vin\u0103 ar fi un asteroid sau o comet\u0103, care s-a pr\u0103bu\u015fit pe ... Cititi mai multe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretele lui Lovendal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/secreteleluilovendal\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-11T18:30:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-11T18:30:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"358\" \/>\n\t<meta property=\"og:image:height\" content=\"239\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scris de\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/person\\\/088691de5dfc346bb0c023e1e52ef5d9\"},\"headline\":\"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?\",\"datePublished\":\"2021-02-11T18:30:06+00:00\",\"dateModified\":\"2021-02-11T18:30:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/\"},\"wordCount\":260,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/dinozauri-cometa.jpg\",\"keywords\":[\"asteroid\",\"astronomie\",\"atmosfer\u0103\",\"comet\u0103\",\"crater\",\"dinozauri\",\"Lun\u0103\",\"P\u0103m\u00e2nt\",\"praf\",\"satelit\"],\"articleSection\":[\"Astronomie\"],\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/\",\"name\":\"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor? - Secretele lui Lovendal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/dinozauri-cometa.jpg\",\"datePublished\":\"2021-02-11T18:30:06+00:00\",\"dateModified\":\"2021-02-11T18:30:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/dinozauri-cometa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/dinozauri-cometa.jpg\",\"width\":358,\"height\":239,\"caption\":\"Imagine: pixabay.com (Commons Creative - free)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#website\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\",\"name\":\"Secretele lui Lovendal\",\"description\":\"Site de secrete, stiinta si metafizica - din 2008 -\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#organization\",\"name\":\"Secretele lui Lovendal\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-SLL-iun-2024-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-SLL-iun-2024-1.jpg\",\"width\":771,\"height\":240,\"caption\":\"Secretele lui Lovendal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/secreteleluilovendal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/person\\\/088691de5dfc346bb0c023e1e52ef5d9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.lovendal.ro\\\/wp52\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor? - Secretele lui Lovendal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/","og_locale":"ro_RO","og_type":"article","og_title":"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?","og_description":"Se \u015ftie c\u0103, potrivit oamenilor de \u015ftiin\u0163\u0103, dinozaurii au disp\u0103rut de pe fa\u0163a p\u0103m\u00e2ntului \u00een urm\u0103 cu 65 de milioane de ani. Ni s-a tot spus c\u0103 de vin\u0103 ar fi un asteroid sau o comet\u0103, care s-a pr\u0103bu\u015fit pe ... Cititi mai multe","og_url":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/","og_site_name":"Secretele lui Lovendal","article_publisher":"https:\/\/www.facebook.com\/secreteleluilovendal","article_published_time":"2021-02-11T18:30:06+00:00","article_modified_time":"2021-02-11T18:30:27+00:00","og_image":[{"width":358,"height":239,"url":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scris de":"admin","Timp estimat pentru citire":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#article","isPartOf":{"@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/"},"author":{"name":"admin","@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/person\/088691de5dfc346bb0c023e1e52ef5d9"},"headline":"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?","datePublished":"2021-02-11T18:30:06+00:00","dateModified":"2021-02-11T18:30:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/"},"wordCount":260,"commentCount":0,"publisher":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#organization"},"image":{"@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg","keywords":["asteroid","astronomie","atmosfer\u0103","comet\u0103","crater","dinozauri","Lun\u0103","P\u0103m\u00e2nt","praf","satelit"],"articleSection":["Astronomie"],"inLanguage":"ro-RO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/","url":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/","name":"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor? - Secretele lui Lovendal","isPartOf":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#primaryimage"},"image":{"@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg","datePublished":"2021-02-11T18:30:06+00:00","dateModified":"2021-02-11T18:30:27+00:00","breadcrumb":{"@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#primaryimage","url":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg","contentUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2021\/02\/dinozauri-cometa.jpg","width":358,"height":239,"caption":"Imagine: pixabay.com (Commons Creative - free)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lovendal.ro\/wp52\/a-mai-avut-pamantul-inca-un-satelit-in-afara-de-luna-in-trecutul-indepartat-acesta-a-fost-de-vina-pentru-disparitia-dinozaurilor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lovendal.ro\/wp52\/"},{"@type":"ListItem","position":2,"name":"A mai avut P\u0103m\u00e2ntul \u00eenc\u0103 un satelit (\u00een afar\u0103 de Luna) \u00een trecutul \u00eendep\u0103rtat? Acesta a fost de vin\u0103 pentru dispari\u0163ia dinozaurilor?"}]},{"@type":"WebSite","@id":"https:\/\/www.lovendal.ro\/wp52\/#website","url":"https:\/\/www.lovendal.ro\/wp52\/","name":"Secretele lui Lovendal","description":"Site de secrete, stiinta si metafizica - din 2008 -","publisher":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lovendal.ro\/wp52\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/www.lovendal.ro\/wp52\/#organization","name":"Secretele lui Lovendal","url":"https:\/\/www.lovendal.ro\/wp52\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/logo\/image\/","url":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2024\/06\/cropped-SLL-iun-2024-1.jpg","contentUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2024\/06\/cropped-SLL-iun-2024-1.jpg","width":771,"height":240,"caption":"Secretele lui Lovendal"},"image":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/secreteleluilovendal"]},{"@type":"Person","@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/person\/088691de5dfc346bb0c023e1e52ef5d9","name":"admin","image":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/secure.gravatar.com\/avatar\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.lovendal.ro\/wp52"]}]}},"_links":{"self":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/posts\/73533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/comments?post=73533"}],"version-history":[{"count":0,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/posts\/73533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/media\/73534"}],"wp:attachment":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/media?parent=73533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/categories?post=73533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/tags?post=73533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}