{"id":69581,"date":"2020-05-23T09:50:51","date_gmt":"2020-05-23T06:50:51","guid":{"rendered":"https:\/\/www.lovendal.ro\/wp52\/?p=69581"},"modified":"2020-05-23T09:50:51","modified_gmt":"2020-05-23T06:50:51","slug":"exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul","status":"publish","type":"post","link":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/","title":{"rendered":"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?"},"content":{"rendered":"<p><a href=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-69582\" src=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg\" alt=\"\" width=\"340\" height=\"339\" srcset=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg 340w, https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta-300x300.jpg 300w, https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta-150x150.jpg 150w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a>O fotografie bizar\u0103 \u015fi controversat\u0103 circul\u0103 din 2019 pe Internet. Ea prezint\u0103 un posibil soldat german (probabil din cel de-al doilea r\u0103zboi mondial) care pare c\u0103 se uit\u0103 pe un&#8230; smartphone! \u015ei nu, nu e vreo iluzie optic\u0103; se observ\u0103 clar c\u0103 soldatul \u0163ine \u00een m\u00e2n\u0103 un smartphone.<\/p>\n<p>Desigur, fanii c\u0103l\u0103toriei \u00een timp vor spune c\u0103 aceast\u0103 fotografie reprezint\u0103 dovada suprem\u0103 c\u0103 aceast\u0103 c\u0103l\u0103torie \u00een timp chiar este fezabil\u0103. \u00cens\u0103, e posibil ca explica\u0163iile s\u0103 fie mai simple dec\u00e2t at\u00e2t. \u015ei \u00eemi vin \u00een minte dou\u0103 explica\u0163ii. Prima: de fapt, fotografia nu e din timpul celui de-al doilea r\u0103zboi mondial, ci din timpurile noastre, \u00een timpul pauzei de la o filmare. &#8222;Soldatul&#8221; german n-ar fi altcineva dec\u00e2t un actor care, \u00eentr-o pauz\u0103, \u00ee\u015fi butoneaz\u0103 telefonul mobil. A doua explica\u0163ie &#8211; telefonul mobil a fost ad\u0103ugat ulterior, prin Photoshop.<\/p>\n<p>Ambele explica\u0163ii logice ar putea c\u0103dea dac\u0103 aceast\u0103 fotografie ar ap\u0103rea \u00een arhivele istorice \u015fi originalul ar ar\u0103ta soldatul cu smartphone-ul \u00een m\u00e2n\u0103. Dac\u0103 ar fi adev\u0103rat, atunci singura explica\u0163ie ar fi cea paranormal\u0103: c\u0103l\u0103toria \u00een timp.<\/p>\n<p><a href=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-69583\" src=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone.jpg\" alt=\"\" width=\"542\" height=\"352\" srcset=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone.jpg 542w, https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-300x195.jpg 300w\" sizes=\"auto, (max-width: 542px) 100vw, 542px\" \/><\/a><em>Sursa: <a href=\"https:\/\/imgur.com\/gallery\/DBJer0N\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>imgur.com<\/strong><\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O fotografie bizar\u0103 \u015fi controversat\u0103 circul\u0103 din 2019 pe Internet. Ea prezint\u0103 un posibil soldat german (probabil din cel de-al doilea r\u0103zboi mondial) care pare c\u0103 se uit\u0103 pe un&#8230; smartphone! \u015ei nu, nu e vreo iluzie optic\u0103; se observ\u0103 &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?\" class=\"read-more button\" href=\"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/#more-69581\" aria-label=\"Cite\u0219te mai multe despre Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?\">Cititi mai multe<\/a><\/p>\n","protected":false},"author":1,"featured_media":69582,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2761],"tags":[979,6826,4554,260,15,10054,597,2757,9812,5061,1658],"class_list":["post-69581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-poze-controversate","tag-actor","tag-calatorie-in-timp","tag-cel-de-al-doilea-razboi-mondial","tag-film","tag-fotografie","tag-iluzie-optica","tag-internet","tag-photoshop","tag-poze-controversate","tag-smartphone","tag-soldat","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!? - Secretele lui Lovendal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?\" \/>\n<meta property=\"og:description\" content=\"O fotografie bizar\u0103 \u015fi controversat\u0103 circul\u0103 din 2019 pe Internet. Ea prezint\u0103 un posibil soldat german (probabil din cel de-al doilea r\u0103zboi mondial) care pare c\u0103 se uit\u0103 pe un&#8230; smartphone! \u015ei nu, nu e vreo iluzie optic\u0103; se observ\u0103 ... Cititi mai multe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretele lui Lovendal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/secreteleluilovendal\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-23T06:50:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"340\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scris de\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/person\\\/088691de5dfc346bb0c023e1e52ef5d9\"},\"headline\":\"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?\",\"datePublished\":\"2020-05-23T06:50:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/soldat-german-smartphone-coperta.jpg\",\"keywords\":[\"actor\",\"c\u0103l\u0103torie \u00een timp\",\"cel de-al doilea r\u0103zboi mondial\",\"film\",\"fotografie\",\"iluzie optic\u0103\",\"Internet\",\"Photoshop\",\"Poze controversate\",\"smartphone\",\"soldat\"],\"articleSection\":[\"Poze controversate\"],\"inLanguage\":\"ro-RO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/\",\"name\":\"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!? - Secretele lui Lovendal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/soldat-german-smartphone-coperta.jpg\",\"datePublished\":\"2020-05-23T06:50:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/soldat-german-smartphone-coperta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/soldat-german-smartphone-coperta.jpg\",\"width\":340,\"height\":339},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#website\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\",\"name\":\"Secretele lui Lovendal\",\"description\":\"Site de secrete, stiinta si metafizica - din 2008 -\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#organization\",\"name\":\"Secretele lui Lovendal\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-SLL-iun-2024-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-SLL-iun-2024-1.jpg\",\"width\":771,\"height\":240,\"caption\":\"Secretele lui Lovendal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/secreteleluilovendal\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lovendal.ro\\\/wp52\\\/#\\\/schema\\\/person\\\/088691de5dfc346bb0c023e1e52ef5d9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.lovendal.ro\\\/wp52\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!? - Secretele lui Lovendal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/","og_locale":"ro_RO","og_type":"article","og_title":"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?","og_description":"O fotografie bizar\u0103 \u015fi controversat\u0103 circul\u0103 din 2019 pe Internet. Ea prezint\u0103 un posibil soldat german (probabil din cel de-al doilea r\u0103zboi mondial) care pare c\u0103 se uit\u0103 pe un&#8230; smartphone! \u015ei nu, nu e vreo iluzie optic\u0103; se observ\u0103 ... Cititi mai multe","og_url":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/","og_site_name":"Secretele lui Lovendal","article_publisher":"https:\/\/www.facebook.com\/secreteleluilovendal","article_published_time":"2020-05-23T06:50:51+00:00","og_image":[{"width":340,"height":339,"url":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scris de":"admin","Timp estimat pentru citire":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/#article","isPartOf":{"@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/"},"author":{"name":"admin","@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/person\/088691de5dfc346bb0c023e1e52ef5d9"},"headline":"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?","datePublished":"2020-05-23T06:50:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/"},"wordCount":225,"publisher":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#organization"},"image":{"@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg","keywords":["actor","c\u0103l\u0103torie \u00een timp","cel de-al doilea r\u0103zboi mondial","film","fotografie","iluzie optic\u0103","Internet","Photoshop","Poze controversate","smartphone","soldat"],"articleSection":["Poze controversate"],"inLanguage":"ro-RO"},{"@type":"WebPage","@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/","url":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/","name":"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!? - Secretele lui Lovendal","isPartOf":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/#primaryimage"},"image":{"@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg","datePublished":"2020-05-23T06:50:51+00:00","breadcrumb":{"@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/#primaryimage","url":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg","contentUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2020\/05\/soldat-german-smartphone-coperta.jpg","width":340,"height":339},{"@type":"BreadcrumbList","@id":"https:\/\/www.lovendal.ro\/wp52\/exista-vreo-explicatie-pentru-aceasta-fotografie-bizara-adica-un-soldat-german-din-cel-de-al-doilea-razboi-mondial-pare-ca-si-butoneaza-smartphone-ul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lovendal.ro\/wp52\/"},{"@type":"ListItem","position":2,"name":"Exist\u0103 vreo explica\u0163ie pentru aceast\u0103 fotografie bizar\u0103? Adic\u0103, un soldat german din cel de-al doilea r\u0103zboi mondial pare c\u0103-\u015fi butoneaz\u0103 smartphone-ul!?"}]},{"@type":"WebSite","@id":"https:\/\/www.lovendal.ro\/wp52\/#website","url":"https:\/\/www.lovendal.ro\/wp52\/","name":"Secretele lui Lovendal","description":"Site de secrete, stiinta si metafizica - din 2008 -","publisher":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lovendal.ro\/wp52\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/www.lovendal.ro\/wp52\/#organization","name":"Secretele lui Lovendal","url":"https:\/\/www.lovendal.ro\/wp52\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/logo\/image\/","url":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2024\/06\/cropped-SLL-iun-2024-1.jpg","contentUrl":"https:\/\/www.lovendal.ro\/wp52\/wp-content\/uploads\/2024\/06\/cropped-SLL-iun-2024-1.jpg","width":771,"height":240,"caption":"Secretele lui Lovendal"},"image":{"@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/secreteleluilovendal"]},{"@type":"Person","@id":"https:\/\/www.lovendal.ro\/wp52\/#\/schema\/person\/088691de5dfc346bb0c023e1e52ef5d9","name":"admin","image":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/secure.gravatar.com\/avatar\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecb9cd41f5f63c9c9b989999a59f6e2639a865ec361e9db054db0679a8f341c2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.lovendal.ro\/wp52"]}]}},"_links":{"self":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/posts\/69581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/comments?post=69581"}],"version-history":[{"count":0,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/posts\/69581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/media\/69582"}],"wp:attachment":[{"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/media?parent=69581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/categories?post=69581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lovendal.ro\/wp52\/wp-json\/wp\/v2\/tags?post=69581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}